{"id":3,"count":5,"description":"","link":"https:\/\/skan3d.com.pl\/index.php\/category\/skanowanie-modelowanie\/","name":"Skanowanie i modelowanie 3D","slug":"skanowanie-modelowanie","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Skanowanie i modelowanie 3D - SKAN3D.COM.PL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skan3d.com.pl\/index.php\/category\/skanowanie-modelowanie\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Skanowanie i modelowanie 3D - SKAN3D.COM.PL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skan3d.com.pl\/index.php\/category\/skanowanie-modelowanie\/\" \/>\n<meta property=\"og:site_name\" content=\"SKAN3D.COM.PL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skan3d.com.pl\/#website\",\"url\":\"https:\/\/skan3d.com.pl\/\",\"name\":\"SKAN3D.COM.PL\",\"description\":\"Przemys\\u0142owe skanery 3D i cyfryzacja przemys\\u0142u\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/skan3d.com.pl\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/skan3d.com.pl\/index.php\/category\/skanowanie-modelowanie\/#webpage\",\"url\":\"https:\/\/skan3d.com.pl\/index.php\/category\/skanowanie-modelowanie\/\",\"name\":\"Skanowanie i modelowanie 3D - SKAN3D.COM.PL\",\"isPartOf\":{\"@id\":\"https:\/\/skan3d.com.pl\/#website\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skan3d.com.pl\/index.php\/category\/skanowanie-modelowanie\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/skan3d.com.pl\/index.php\/wp-json\/wp\/v2\/categories\/3"}],"collection":[{"href":"https:\/\/skan3d.com.pl\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/skan3d.com.pl\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/skan3d.com.pl\/index.php\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}